{"id":1250,"date":"2018-12-03T16:41:14","date_gmt":"2018-12-03T09:41:14","guid":{"rendered":"https:\/\/www.iamchild.org?page_id=1250"},"modified":"2018-12-03T16:42:48","modified_gmt":"2018-12-03T09:42:48","slug":"credit-card","status":"publish","type":"page","link":"https:\/\/www.iamchild.org\/en\/donate\/credit-card\/","title":{"rendered":"Donate via credit card"},"content":{"rendered":"<div id=\"pl-1250\"  class=\"panel-layout\" ><div id=\"pg-1250-0\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-1250-0\" data-stretch-type=\"full-stretched\" ><div id=\"pgc-1250-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1250-0-0-0\" class=\"so-panel widget widget_sow-hero panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"so-widget-sow-hero so-widget-sow-hero-default-2ed901d9b768-1250 so-widget-fittext-wrapper\" data-fit-text-compressor=\"0.85\"><div class=\"sow-slider-base\" style=\"display: none\"><ul class=\"sow-slider-images\" data-settings=\"{&quot;pagination&quot;:true,&quot;speed&quot;:800,&quot;timeout&quot;:8000,&quot;paused&quot;:false,&quot;pause_on_hover&quot;:false,&quot;swipe&quot;:true,&quot;nav_always_show_desktop&quot;:&quot;&quot;,&quot;nav_always_show_mobile&quot;:&quot;&quot;,&quot;breakpoint&quot;:&quot;780px&quot;,&quot;unmute&quot;:false}\">\t\t<li class=\"sow-slider-image  sow-slider-image-cover\" style=\"background-color: #0858b7\" >\n\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t<div class=\"sow-slider-image-wrapper\">\n\t\t\t\t<h1 style=\"text-align: center\">Donate via Credit Card<\/h1>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"sow-slider-image-overlay sow-slider-image-cover\" style=\"background-image: url(https:\/\/www.iamchild.org\/wp-content\/uploads\/2018\/10\/children-602967_960_720@2x.png);opacity: 0.6\"  ><\/div>\t\t<\/li>\n\t\t<\/ul>\t\t\t\t<ol class=\"sow-slider-pagination\">\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"0\" aria-label=\"display slide 1\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t<\/ol>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-next\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"next\" aria-label=\"next slide\" data-action=\"next\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-right\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-prev\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"previous\" aria-label=\"previous slide\" data-action=\"prev\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-left\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-1250-1\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-1250-1\" ><div id=\"pgc-1250-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1250-1-0-0\" class=\"so-panel widget widget_yith_wc_donations_form panel-first-child\" data-index=\"1\" ><h3 class=\"widget-title\">\u0e01\u0e23\u0e2d\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19<\/h3><div class=\"ywcds_form_container\">\n\t<form id=\"ywcds_add_donation_form\" method=\"get\">\n\t\t<div class=\"ywcds_amount_field\">\n\t\t\t<label for=\"ywcds_amount\"><\/label>\n\t\t\t<input type=\"text\" class=\"ywcds_amount\" name=\"ywcds_amount\"\/>\n\t\t<\/div>\n\t\t<div class=\"ywcds_button_field\">\n\t\t\t<input type=\"hidden\" class=\"ywcds_product_id\" name=\"add_donation_to_cart\" value=\"1090\" \/>\n\t\t\t<input type=\"submit\" name=\"ywcds_submit_widget\" class=\"ywcds_submit_widget button alt \" value=\"Add donation\" \/>\n\t\t<\/div>\n\t<\/form>\n\t<img src=\"https:\/\/www.iamchild.org\/wp-content\/plugins\/yith-donations-for-woocommerce\/assets\/images\/ajax-loader.gif\" class=\"ajax-loading\" alt=\"loading\" width=\"16\" height=\"16\" style=\"visibility:hidden\" \/>\n\t<div class=\"ywcds_message woocommerce-message\" style=\"display: none;\"><\/div>\n<\/div>\n<\/div><div id=\"panel-1250-1-0-1\" class=\"so-panel widget widget_sow-button panel-last-child\" data-index=\"2\" ><div class=\"so-widget-sow-button so-widget-sow-button-flat-ca7df736062e-1250\"><div class=\"ow-button-base ow-button-align-center\">\n\t<a href=\"https:\/\/www.iamchild.org\/checkout\" class=\"ow-icon-placement-left ow-button-hover\" \t\t>\n\t\t<span>\n\t\t\t\n\t\t\t\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e14\u0e49\u0e27\u0e22 Paypal\t\t<\/span>\n\t<\/a>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-1250-2\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-1250-2\" ><div id=\"pgc-1250-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1250-2-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child panel-last-child\" data-index=\"3\" ><div class=\"panel-widget-style panel-widget-style-for-1250-2-0-0\" ><div class=\"so-widget-sow-headline so-widget-sow-headline-default-51521e26af4c-1250\"><div class=\"sow-headline-container \">\n\t<h4 class='sow-headline'>\u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e43\u0e1a\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e33\u0e44\u0e1b\u0e25\u0e14\u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e35<\/h4><\/div><\/div><\/div><\/div><\/div><div id=\"pgc-1250-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-1250-2-1-0\" class=\"so-panel widget widget_sow-button panel-first-child panel-last-child\" data-index=\"4\" ><div class=\"so-widget-sow-button so-widget-sow-button-flat-ff3dce24edc1-1250\"><div class=\"ow-button-base ow-button-align-left\">\n\t<a href=\"#\" class=\"ow-icon-placement-left ow-button-hover\" \t\t>\n\t\t<span>\n\t\t\t\n\t\t\t\u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\t\t<\/span>\n\t<\/a>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-1250-3\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1250-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1250-3-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"5\" ><div class=\"panel-widget-style panel-widget-style-for-1250-3-0-0\" ><div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p style=\"text-align: center; font-size: 14px;\">\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e14\u0e47\u0e01 (\u0e21\u0e1e\u0e14.) \u0e40\u0e1b\u0e47\u0e19\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e25\u0e33\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48 179<br \/>\n\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e14\u0e47\u0e01 \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e43\u0e1a\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e44\u0e1b\u0e25\u0e14\u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e35\u0e44\u0e14\u0e49<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Donate via Credit Card \u0e01\u0e23\u0e2d\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e14\u0e49\u0e27\u0e22 Paypal \u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e43\u0e1a\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e33\u0e44\u0e1b\u0e25\u0e14\u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48 \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e14\u0e47\u0e01 (\u0e21\u0e1e\u0e14.) \u0e40\u0e1b\u0e47\u0e19\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e25\u0e33\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48 179 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e14\u0e47\u0e01 \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e43\u0e1a\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e44\u0e1b\u0e25\u0e14\u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e35\u0e44\u0e14\u0e49<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":1201,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.iamchild.org\/en\/wp-json\/wp\/v2\/pages\/1250\/"}],"collection":[{"href":"https:\/\/www.iamchild.org\/en\/wp-json\/wp\/v2\/pages\/"}],"about":[{"href":"https:\/\/www.iamchild.org\/en\/wp-json\/wp\/v2\/types\/page\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.iamchild.org\/en\/wp-json\/wp\/v2\/users\/7\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iamchild.org\/en\/wp-json\/wp\/v2\/comments\/?post=1250"}],"version-history":[{"count":1,"href":"https:\/\/www.iamchild.org\/en\/wp-json\/wp\/v2\/pages\/1250\/revisions\/"}],"predecessor-version":[{"id":1265,"href":"https:\/\/www.iamchild.org\/en\/wp-json\/wp\/v2\/pages\/1250\/revisions\/1265\/"}],"up":[{"embeddable":true,"href":"https:\/\/www.iamchild.org\/en\/wp-json\/wp\/v2\/pages\/1201\/"}],"wp:attachment":[{"href":"https:\/\/www.iamchild.org\/en\/wp-json\/wp\/v2\/media\/?parent=1250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}